{"id":600,"date":"2020-01-08T10:08:37","date_gmt":"2020-01-08T09:08:37","guid":{"rendered":"http:\/\/anwaltskanzlei-krummel.de\/cms\/?p=600"},"modified":"2020-01-10T13:15:36","modified_gmt":"2020-01-10T12:15:36","slug":"neue-kindesunterhaltsbetraege-zum-jahresstart","status":"publish","type":"post","link":"https:\/\/anwaltskanzlei-krummel.de\/cms\/neue-kindesunterhaltsbetraege-zum-jahresstart\/","title":{"rendered":"Neue Kindesunterhaltsbetr\u00e4ge zum Jahresstart"},"content":{"rendered":"<p>Ab 01.01.2020 erh\u00f6hen sich die Unterhaltsbetr\u00e4ge, die Kindern zustehen, wenn sie von einem Elternteil getrennt leben. Dies muss unter Umst\u00e4nden auch beim Wechselmodell Ber\u00fccksichtigung finden, sodass rechtzeitige Information f\u00fcr alle Beteiligten wichtig ist, um Streitigkeiten vorzubeugen.<\/p>\n<p>Die Betr\u00e4ge in der niedrigsten Einkommensstufe haben sich auf 369,00 \u20ac f\u00fcr Kinder bis zum 6. Geburtstag (alt: 354,00 \u20ac), auf 424,00 \u20ac f\u00fcr Kinder bis zum 12. Geburtstag (alt: 406,00 \u20ac) und auf 497,00 \u20ac f\u00fcr Kinder bis zum 18. Geburtstag (alt: 476,00 \u20ac) erh\u00f6ht. F\u00fcr Kinder \u00fcber 18 Jahre f\u00e4llt die Erh\u00f6hung mit 3,00 \u20ac (von 527,00 \u20ac auf 530,00 \u20ac) geringer aus. Das jeweilige staatliche Kindergeld muss bei der Ermittlung der Zahlbetr\u00e4ge ber\u00fccksichtigt werden.<\/p>\n<p>Auch die Unterhaltsvorschussbetr\u00e4ge, die vom Staat gezahlt werden, wenn der nichterziehende Elternteil nicht leistungsf\u00e4hig ist, wurden erh\u00f6ht.<\/p>\n<p>Der notwendige Selbstbehalt gegen\u00fcber minderj\u00e4hrigen Kindern betr\u00e4gt beim Nichterwerbst\u00e4tigen nunmehr 960,00 \u20ac und beim Erwerbst\u00e4tigen 1.160,00 \u20ac, wobei Kosten f\u00fcr die Unterkunft (warm) in H\u00f6he von 430,00 \u20ac enthalten sind.<\/p>\n<p>Leider wird in der Praxis oft \u00fcbersehen, dass die Problematik des Kindesunterhaltes auch bei Wechselmodell und unterschiedlichen Einkommensverh\u00e4ltnissen der Eltern eine Rolle spielt. Es kann trotz gleichartigem Versorgungsaufwand dazu kommen, dass auch bei regelm\u00e4\u00dfig wechselnder Betreuung des Kindes ein Elternteil Kindesunterhalt zahlen muss. Pr\u00e4ventiv kann nur zu rechtzeitiger individueller und juristisch fundierter Pr\u00fcfung geraten werden.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Ab 01.01.2020 erh\u00f6hen sich die Unterhaltsbetr\u00e4ge, die Kindern zustehen, wenn sie von einem Elternteil getrennt leben. Dies muss unter Umst\u00e4nden auch beim Wechselmodell Ber\u00fccksichtigung finden, sodass rechtzeitige Information f\u00fcr alle Beteiligten wichtig ist, um Streitigkeiten vorzubeugen. Die Betr\u00e4ge in der niedrigsten Einkommensstufe haben sich auf 369,00 \u20ac f\u00fcr Kinder bis zum 6. Geburtstag (alt: 354,00 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1],"tags":[],"class_list":["post-600","post","type-post","status-publish","format-standard","hentry","category-familienrecht","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/posts\/600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/comments?post=600"}],"version-history":[{"count":1,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/posts\/600\/revisions"}],"predecessor-version":[{"id":601,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/posts\/600\/revisions\/601"}],"wp:attachment":[{"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/media?parent=600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/categories?post=600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/tags?post=600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}