{"id":390,"date":"2017-05-24T11:53:08","date_gmt":"2017-05-24T09:53:08","guid":{"rendered":"http:\/\/anwaltskanzlei-krummel.de\/cms\/?p=390"},"modified":"2017-05-24T11:53:08","modified_gmt":"2017-05-24T09:53:08","slug":"gartenpflege-und-betriebskostenabrechnung","status":"publish","type":"post","link":"https:\/\/anwaltskanzlei-krummel.de\/cms\/gartenpflege-und-betriebskostenabrechnung\/","title":{"rendered":"Gartenpflege und Betriebskostenabrechnung"},"content":{"rendered":"<p>Die B\u00e4ume haben gr\u00fcne Bl\u00e4tter, der Rasen w\u00e4chst &#8211; die Vegetationsperiode hat Fahrt aufgenommen. Die urbane Bebauung ist zunehmend durch Gemeinschaftsg\u00e4rten gepr\u00e4gt. Gerade bei Mehrfamilienh\u00e4usern, bei denen die Mieter zum Teil die Gr\u00fcnfl\u00e4chen nicht einmal nutzen d\u00fcrfen, legt der Vermieter oder ein von ihm beauftragtes Unternehmen Hand an, um zu pflegen. J\u00e4hrlich gibt es dann Streit, was auf Betriebskostenabrechnung umgelegt werden kann.<\/p>\n<p>Die Kosten, die regelm\u00e4\u00dfig umgelegt werden, betreffen das Rasenm\u00e4hen, das Unkrautj\u00e4ten, die Bew\u00e4sserung der Gartenanteile und die Entsorgung der Gartenabf\u00e4lle. Streit gibt es regelm\u00e4\u00dfig beim Beschneiden von Str\u00e4uchern und B\u00e4umen. Es herrscht Einigkeit dar\u00fcber, dass die komplette Umgestaltung eines Gartens oder eine Neuanlage nicht zu den laufenden Betriebskosten geh\u00f6ren, wohl aber der wiederkehrende Kulturschnitt. Auch wenn ein kranker Baum beseitigt werden muss, d\u00fcrfen die Kosten der Ersatzbepflanzung den Mietern in Rechnung gestellt werden. Da es bei solchen F\u00e4llen oft ratsam ist, nicht nur den g\u00e4rtnerischen Teil gr\u00fcndlich vorzubereiten, sondern auch den juristischen, sollte das Vorgehen zeitig auch mit fachkundigem Rat untersetzt werden.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Die B\u00e4ume haben gr\u00fcne Bl\u00e4tter, der Rasen w\u00e4chst &#8211; die Vegetationsperiode hat Fahrt aufgenommen. Die urbane Bebauung ist zunehmend durch Gemeinschaftsg\u00e4rten gepr\u00e4gt. Gerade bei Mehrfamilienh\u00e4usern, bei denen die Mieter zum Teil die Gr\u00fcnfl\u00e4chen nicht einmal nutzen d\u00fcrfen, legt der Vermieter oder ein von ihm beauftragtes Unternehmen Hand an, um zu pflegen. J\u00e4hrlich gibt es dann [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-390","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/posts\/390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/comments?post=390"}],"version-history":[{"count":2,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/posts\/390\/revisions"}],"predecessor-version":[{"id":392,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/posts\/390\/revisions\/392"}],"wp:attachment":[{"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/media?parent=390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/categories?post=390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anwaltskanzlei-krummel.de\/cms\/wp-json\/wp\/v2\/tags?post=390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}